{"id":18441,"date":"2024-12-12T06:43:30","date_gmt":"2024-12-12T09:43:30","guid":{"rendered":"https:\/\/ubajaranoticias.com.br\/index.php\/2024\/12\/12\/sine-municipal-de-sorocaba-oferece-159-vagas-de-emprego-na-quinta-feira-12-agencia-de-noticias\/"},"modified":"2024-12-12T06:43:30","modified_gmt":"2024-12-12T09:43:30","slug":"sine-municipal-de-sorocaba-oferece-159-vagas-de-emprego-na-quinta-feira-12-agencia-de-noticias","status":"publish","type":"post","link":"https:\/\/ubajaranoticias.com.br\/index.php\/2024\/12\/12\/sine-municipal-de-sorocaba-oferece-159-vagas-de-emprego-na-quinta-feira-12-agencia-de-noticias\/","title":{"rendered":"Sine Municipal de Sorocaba oferece 159 vagas de emprego na quinta-feira (12) \u2013 Ag\u00eancia de Not\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"col\">\n<p class=\"mt-0\">\n                        <strong><br \/>\n                            <span class=\"far fa-calendar mr-1 mt-2\"\/><br \/>\n                            11 de dezembro de 2024<br \/>\n                            <span class=\"far fa-clock ml-3 mt-2\"\/><br \/>\n                            16:04<br \/>\n                        <\/strong>\n                    <\/p>\n<p class=\"mb-0\">Por: <strong>Lu\u00eds Gustavo Adabro<\/strong><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<p>O Sine Municipal de Sorocaba, antigo Posto de Atendimento ao Trabalhador (PAT) de Sorocaba, ligado \u00e0 Secretaria de Rela\u00e7\u00f5es do Trabalho e Qualifica\u00e7\u00e3o Profissional (Sert), da Prefeitura de Sorocaba, oferecer\u00e1, na quinta-feira (12), 159 vagas de trabalho na cidade.<\/p>\n<p>Os mun\u00edcipes podem se candidatar comparecendo ao Sine Municipal de Sorocaba no Centro e a sua unidade m\u00f3vel, sem a necessidade de agendamento pr\u00e9vio, ou ainda na Casa do Cidad\u00e3o mais pr\u00f3xima de sua resid\u00eancia.<\/p>\n<p>Para tanto, \u00e9 necess\u00e1rio que os interessados estejam munidos de carteira de trabalho, CPF e RG. No PAT Central, o mun\u00edcipe tamb\u00e9m tem a oportunidade de enviar curr\u00edculo pelos computadores dispon\u00edveis para uso da popula\u00e7\u00e3o.<\/p>\n<p>O Poder P\u00fablico Municipal tamb\u00e9m disponibiliza os servi\u00e7os do Sine para todo cidad\u00e3o que deseja realizar a consulta sobre vagas de emprego. Ela pode ser feita pelo site: empregabrasil.mte.gov.br e pelo aplicativo para celular Sinefacil. O Sine Municipal de Sorocaba est\u00e1 localizado na Rua Cel. Cavalheiros, 353, no Centro, e funciona de segunda a sexta-feira, das 8h \u00e0s 16h, assim como as Casas do Cidad\u00e3o.<\/p>\n<p>O mun\u00edcipe que desejar, ainda pode contatar o Sine Municipal Sorocaba pelo WhatsApp: (15) 99149-2474. Na quinta-feira (12), o PAT M\u00f3vel estar\u00e1 dispon\u00edvel, das 8h30 \u00e0s 12h, no Centro de Refer\u00eancia em Assist\u00eancia Social (CRAS) Aparecidinha, localizado na Rua Jos\u00e9 Braz Correia, 100, Aparecidinha.<\/p>\n<p>Segue, em anexo, todas as vagas de empregos dispon\u00edveis no Sine Municipal na\u00a0quinta-feira (12).<\/p>\n<p>VAGAS PAT 12-12<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>11 de dezembro de 2024 16:04 Por: Lu\u00eds Gustavo Adabro O Sine Municipal de Sorocaba, antigo Posto de Atendimento ao Trabalhador (PAT) de Sorocaba, ligado \u00e0 Secretaria de Rela\u00e7\u00f5es do Trabalho e Qualifica\u00e7\u00e3o Profissional (Sert), da Prefeitura de Sorocaba, oferecer\u00e1, na quinta-feira (12), 159 vagas de trabalho na cidade. Os mun\u00edcipes podem se candidatar comparecendo &#8230; <a title=\"Sine Municipal de Sorocaba oferece 159 vagas de emprego na quinta-feira (12) \u2013 Ag\u00eancia de Not\u00edcias\" class=\"read-more\" href=\"https:\/\/ubajaranoticias.com.br\/index.php\/2024\/12\/12\/sine-municipal-de-sorocaba-oferece-159-vagas-de-emprego-na-quinta-feira-12-agencia-de-noticias\/\" aria-label=\"Read more about Sine Municipal de Sorocaba oferece 159 vagas de emprego na quinta-feira (12) \u2013 Ag\u00eancia de Not\u00edcias\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-18441","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18441"}],"version-history":[{"count":0,"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18441\/revisions"}],"wp:attachment":[{"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubajaranoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}